{"id":10770,"date":"2025-02-14T14:15:50","date_gmt":"2025-02-14T07:15:50","guid":{"rendered":"https:\/\/www.culture.cmru.ac.th\/web\/?p=10770"},"modified":"2025-02-14T14:15:51","modified_gmt":"2025-02-14T07:15:51","slug":"%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%a0%e0%b8%b1%e0%b8%8f%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87-4","status":"publish","type":"post","link":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770","title":{"rendered":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&#8221; \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2568 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&#8221; \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35) \u0e15.\u0e2a\u0e38\u0e40\u0e17\u0e1e \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e1e\u0e23\u0e30\u0e04\u0e23\u0e39\u0e18\u0e35\u0e23\u0e2a\u0e38\u0e15\u0e1e\u0e08\u0e19\u0e4c,\u0e14\u0e23. \u0e40\u0e08\u0e49\u0e32\u0e2d\u0e32\u0e27\u0e32\u0e2a\u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e2a\u0e21\u0e42\u0e20\u0e2a 650 \u0e1b\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e37\u0e1a\u0e2a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e14\u0e34\u0e19\u0e02\u0e36\u0e49\u0e19\u0e14\u0e2d\u0e22 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38 \u0e2d\u0e32\u0e23\u0e32\u0e18\u0e19\u0e32\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e40\u0e01\u0e2a\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32\u0e1a\u0e38\u0e1b\u0e1c\u0e32\u0e25\u0e49\u0e32\u0e19\u0e14\u0e27\u0e07 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1b\u0e35 \u0e1e.\u0e28. 2567 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e41\u0e25\u0e30\u0e43\u0e19\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e44\u0e14\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e2b\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e07 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 &#8211; 12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2568 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2568<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e14\u0e49\u0e2d\u0e31\u0e0d\u0e40\u0e0a\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e2a\u0e32\u0e23\u0e35\u0e23\u0e34\u0e01\u0e18\u0e32\u0e15\u0e38 \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e30\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e1a\u0e32\u0e23\u0e21\u0e35\u0e18\u0e23\u0e23\u0e21\u0e43\u0e1a\u0e25\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e1e\u0e0d\u0e32\u0e04\u0e0a\u0e2a\u0e32\u0e23 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e40\u0e0a\u0e37\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e40\u0e0a\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e2a\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e27\u0e31\u0e14\u0e2a\u0e32\u0e21\u0e22\u0e2d\u0e1a(\u0e23\u0e49\u0e32\u0e07) \u0e41\u0e25\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e39\u0e48\u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02) \u0e13 \u0e21\u0e13\u0e11\u0e25\u0e1e\u0e34\u0e18\u0e35\u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e1e\u0e34\u0e18\u0e35\u0e23\u0e31\u0e1a\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e31\u0e22\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e27\u0e23\u0e27\u0e07\u0e28\u0e4c\u0e40\u0e18\u0e2d \u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e20\u0e32\u0e08\u0e38\u0e11\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e42\u0e14\u0e22\u0e19\u0e32\u0e22\u0e27\u0e35\u0e23\u0e1e\u0e07\u0e28\u0e4c \u0e24\u0e17\u0e18\u0e34\u0e4c\u0e23\u0e2d\u0e14 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1e\u0e23\u0e30\u0e18\u0e23\u0e23\u0e21\u0e40\u0e17\u0e28\u0e19\u0e32\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19\u0e1a\u0e32\u0e23\u0e21\u0e35 10 \u0e17\u0e31\u0e28<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e34\u0e15\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e23\u0e27\u0e22\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1c\u0e49\u0e32\u0e1a\u0e0e \u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e34\u0e15\u0e01\u0e32\u0e23\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32\u0e08\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e23\u0e39\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e42\u0e2e\u0e07\u0e40\u0e2e\u0e35\u0e22\u0e19\u0e2a\u0e37\u0e1a\u0e2a\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e34\u0e15\u0e01\u0e32\u0e23\u0e08\u0e32\u0e23\u0e43\u0e1a\u0e25\u0e32\u0e19\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477712196_1205218184938435_4464818368665958161_n.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"450\" data-id=\"10774\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477712196_1205218184938435_4464818368665958161_n.jpg\" alt=\"\" class=\"wp-image-10774\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477712196_1205218184938435_4464818368665958161_n.jpg 600w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477712196_1205218184938435_4464818368665958161_n-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477571638_1205220388271548_361321634505843639_n.jpg\"><img decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10776\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477571638_1205220388271548_361321634505843639_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10776\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477571638_1205220388271548_361321634505843639_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477571638_1205220388271548_361321634505843639_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477571638_1205220388271548_361321634505843639_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477571638_1205220388271548_361321634505843639_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477571638_1205220388271548_361321634505843639_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n.jpg\"><img decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10775\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10775\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477183829_1205220054938248_4688748328964127652_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10780\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477183829_1205220054938248_4688748328964127652_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10780\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477183829_1205220054938248_4688748328964127652_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477183829_1205220054938248_4688748328964127652_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477183829_1205220054938248_4688748328964127652_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477183829_1205220054938248_4688748328964127652_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477183829_1205220054938248_4688748328964127652_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477689731_1205219918271595_6492806505261890369_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10777\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477689731_1205219918271595_6492806505261890369_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10777\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477689731_1205219918271595_6492806505261890369_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477689731_1205219918271595_6492806505261890369_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477689731_1205219918271595_6492806505261890369_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477689731_1205219918271595_6492806505261890369_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477689731_1205219918271595_6492806505261890369_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477847137_1205219808271606_8088642403237144568_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10778\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477847137_1205219808271606_8088642403237144568_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10778\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477847137_1205219808271606_8088642403237144568_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477847137_1205219808271606_8088642403237144568_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477847137_1205219808271606_8088642403237144568_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477847137_1205219808271606_8088642403237144568_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477847137_1205219808271606_8088642403237144568_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477205496_1205219511604969_588930869541750287_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10781\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477205496_1205219511604969_588930869541750287_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10781\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477205496_1205219511604969_588930869541750287_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477205496_1205219511604969_588930869541750287_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477205496_1205219511604969_588930869541750287_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477205496_1205219511604969_588930869541750287_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477205496_1205219511604969_588930869541750287_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477975398_1205219281604992_3314166327471999950_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10779\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477975398_1205219281604992_3314166327471999950_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10779\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477975398_1205219281604992_3314166327471999950_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477975398_1205219281604992_3314166327471999950_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477975398_1205219281604992_3314166327471999950_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477975398_1205219281604992_3314166327471999950_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477975398_1205219281604992_3314166327471999950_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478332440_1205219181605002_2988503121126635650_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10782\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478332440_1205219181605002_2988503121126635650_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10782\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478332440_1205219181605002_2988503121126635650_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478332440_1205219181605002_2988503121126635650_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478332440_1205219181605002_2988503121126635650_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478332440_1205219181605002_2988503121126635650_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478332440_1205219181605002_2988503121126635650_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477400301_1205219134938340_8621448695145310778_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10783\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477400301_1205219134938340_8621448695145310778_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10783\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477400301_1205219134938340_8621448695145310778_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477400301_1205219134938340_8621448695145310778_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477400301_1205219134938340_8621448695145310778_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477400301_1205219134938340_8621448695145310778_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477400301_1205219134938340_8621448695145310778_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477311434_1205219111605009_7053872151913774330_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10784\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477311434_1205219111605009_7053872151913774330_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10784\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477311434_1205219111605009_7053872151913774330_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477311434_1205219111605009_7053872151913774330_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477311434_1205219111605009_7053872151913774330_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477311434_1205219111605009_7053872151913774330_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477311434_1205219111605009_7053872151913774330_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478901866_1205219051605015_2647604239909026870_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10785\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478901866_1205219051605015_2647604239909026870_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10785\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478901866_1205219051605015_2647604239909026870_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478901866_1205219051605015_2647604239909026870_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478901866_1205219051605015_2647604239909026870_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478901866_1205219051605015_2647604239909026870_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/478901866_1205219051605015_2647604239909026870_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640056_1205219068271680_8842144445795058159_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10787\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640056_1205219068271680_8842144445795058159_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10787\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640056_1205219068271680_8842144445795058159_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640056_1205219068271680_8842144445795058159_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640056_1205219068271680_8842144445795058159_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640056_1205219068271680_8842144445795058159_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640056_1205219068271680_8842144445795058159_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477289499_1205218904938363_1213284078378132537_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10786\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477289499_1205218904938363_1213284078378132537_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10786\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477289499_1205218904938363_1213284078378132537_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477289499_1205218904938363_1213284078378132537_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477289499_1205218904938363_1213284078378132537_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477289499_1205218904938363_1213284078378132537_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477289499_1205218904938363_1213284078378132537_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477992457_1205218858271701_4251602663898175789_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10788\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477992457_1205218858271701_4251602663898175789_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10788\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477992457_1205218858271701_4251602663898175789_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477992457_1205218858271701_4251602663898175789_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477992457_1205218858271701_4251602663898175789_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477992457_1205218858271701_4251602663898175789_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477992457_1205218858271701_4251602663898175789_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477772183_1205218754938378_4524445763309813112_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10789\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477772183_1205218754938378_4524445763309813112_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10789\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477772183_1205218754938378_4524445763309813112_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477772183_1205218754938378_4524445763309813112_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477772183_1205218754938378_4524445763309813112_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477772183_1205218754938378_4524445763309813112_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/477772183_1205218754938378_4524445763309813112_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476641633_1205218698271717_8987744095639336746_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"10790\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476641633_1205218698271717_8987744095639336746_n-1024x769.jpg\" alt=\"\" class=\"wp-image-10790\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476641633_1205218698271717_8987744095639336746_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476641633_1205218698271717_8987744095639336746_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476641633_1205218698271717_8987744095639336746_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476641633_1205218698271717_8987744095639336746_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476641633_1205218698271717_8987744095639336746_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2568 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&#8221;<\/p>\n","protected":false},"author":1,"featured_media":10775,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-10770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&quot; \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35) - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&quot; \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35) - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2568 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ilaccmru\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T07:15:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-14T07:15:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"weerapich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"weerapich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770\"},\"author\":{\"name\":\"weerapich\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/person\\\/3b7d33d128d6b2fc45aa53883d31a0d8\"},\"headline\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&#8221; \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35)\",\"datePublished\":\"2025-02-14T07:15:50+00:00\",\"dateModified\":\"2025-02-14T07:15:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770\"},\"wordCount\":1,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/476640212_1205220158271571_208925973209005556_n.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02\\\" \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35) - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/476640212_1205220158271571_208925973209005556_n.jpg\",\"datePublished\":\"2025-02-14T07:15:50+00:00\",\"dateModified\":\"2025-02-14T07:15:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770#primaryimage\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/476640212_1205220158271571_208925973209005556_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/476640212_1205220158271571_208925973209005556_n.jpg\",\"width\":2048,\"height\":1537},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/10770#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&#8221; \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/\",\"name\":\"ACI : Arts and Culture Institute\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e21\u0e23\u0e14\u0e01\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-xl.png\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-xl.png\",\"width\":1080,\"height\":1080,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ilaccmru\\\/\",\"https:\\\/\\\/youtube.com\\\/@culturecmru\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/person\\\/3b7d33d128d6b2fc45aa53883d31a0d8\",\"name\":\"weerapich\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"caption\":\"weerapich\"},\"sameAs\":[\"https:\\\/\\\/culture.cmru.ac.th\\\/web\"],\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/author\\\/weerapich\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02\" \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35) - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770","og_locale":"th_TH","og_type":"article","og_title":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02\" \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35) - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","og_description":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2568 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e42\u0e14\u0e22\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02\"","og_url":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","article_publisher":"https:\/\/www.facebook.com\/ilaccmru\/","article_published_time":"2025-02-14T07:15:50+00:00","article_modified_time":"2025-02-14T07:15:51+00:00","og_image":[{"width":2048,"height":1537,"url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n.jpg","type":"image\/jpeg"}],"author":"weerapich","twitter_card":"summary_large_image","twitter_misc":{"Written by":"weerapich","Est. reading time":"5 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770#article","isPartOf":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770"},"author":{"name":"weerapich","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/person\/3b7d33d128d6b2fc45aa53883d31a0d8"},"headline":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&#8221; \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35)","datePublished":"2025-02-14T07:15:50+00:00","dateModified":"2025-02-14T07:15:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770"},"wordCount":1,"commentCount":0,"publisher":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770#primaryimage"},"thumbnailUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.culture.cmru.ac.th\/web\/th\/10770#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770","url":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02\" \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35) - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","isPartOf":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770#primaryimage"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770#primaryimage"},"thumbnailUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n.jpg","datePublished":"2025-02-14T07:15:50+00:00","dateModified":"2025-02-14T07:15:51+00:00","breadcrumb":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.culture.cmru.ac.th\/web\/th\/10770"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770#primaryimage","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n.jpg","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/02\/476640212_1205220158271571_208925973209005556_n.jpg","width":2048,"height":1537},{"@type":"BreadcrumbList","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/10770#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.culture.cmru.ac.th\/web\/th\/home"},{"@type":"ListItem","position":2,"name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u201c\u0e17\u0e32\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e27\u0e22\u0e2e\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e44\u0e2b\u0e27\u0e49\u0e2a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02&#8221; \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e1e\u0e47\u0e0d\u0e21\u0e32\u0e06\u0e1a\u0e39\u0e0a\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e23\u0e39\u0e1a\u0e32 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e13 \u0e27\u0e31\u0e14\u0e1c\u0e32\u0e25\u0e32\u0e14 (\u0e2a\u0e01\u0e17\u0e32\u0e04\u0e32\u0e21\u0e35)"}]},{"@type":"WebSite","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#website","url":"https:\/\/www.culture.cmru.ac.th\/web\/","name":"ACI : Arts and Culture Institute","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e21\u0e23\u0e14\u0e01\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19","publisher":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.culture.cmru.ac.th\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","url":"https:\/\/www.culture.cmru.ac.th\/web\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/logo\/image\/","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/logo-xl.png","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/logo-xl.png","width":1080,"height":1080,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ilaccmru\/","https:\/\/youtube.com\/@culturecmru"]},{"@type":"Person","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/person\/3b7d33d128d6b2fc45aa53883d31a0d8","name":"weerapich","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","caption":"weerapich"},"sameAs":["https:\/\/culture.cmru.ac.th\/web"],"url":"https:\/\/www.culture.cmru.ac.th\/web\/author\/weerapich"}]}},"_links":{"self":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts\/10770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/comments?post=10770"}],"version-history":[{"count":0,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts\/10770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/media\/10775"}],"wp:attachment":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/media?parent=10770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/categories?post=10770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/tags?post=10770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}