{"id":11079,"date":"2025-03-21T09:33:57","date_gmt":"2025-03-21T02:33:57","guid":{"rendered":"https:\/\/www.culture.cmru.ac.th\/web\/?p=11079"},"modified":"2025-03-21T09:33:58","modified_gmt":"2025-03-21T02:33:58","slug":"%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b9%80%e0%b8%8a%e0%b8%b4%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81","status":"publish","type":"post","link":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079","title":{"rendered":"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2568 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e2b\u0e25\u0e32 \u0e27\u0e07\u0e28\u0e4c\u0e1b\u0e49\u0e2d \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e28.\u0e14\u0e23.\u0e19\u0e34\u0e42\u0e25\u0e1a\u0e25 \u0e27\u0e34\u0e21\u0e25\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e0a\u0e31\u0e22 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14 \u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e17\u0e23\u0e07\u0e04\u0e38\u0e13\u0e27\u0e38\u0e12\u0e34 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e04\u0e38\u0e13\u0e1b\u0e23\u0e35\u0e0a\u0e32 \u0e0a\u0e31\u0e22\u0e0a\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e1c\u0e28.\u0e14\u0e23.\u0e0a\u0e38\u0e15\u0e34\u0e21\u0e31\u0e19\u0e15\u0e4c \u0e2a\u0e30\u0e2a\u0e2d\u0e07 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1e\u0e19\u0e34\u0e14\u0e32 \u0e41\u0e1b\u0e07\u0e27\u0e07\u0e28\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e27\u0e34\u0e13\u0e13\u0e4c \u0e04\u0e38\u0e13\u0e22\u0e28\u0e22\u0e34\u0e48\u0e07<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485630043_1235415018585418_252535921160899900_n.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"11084\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485630043_1235415018585418_252535921160899900_n-1024x769.jpg\" alt=\"\" class=\"wp-image-11084\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485630043_1235415018585418_252535921160899900_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485630043_1235415018585418_252535921160899900_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485630043_1235415018585418_252535921160899900_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485630043_1235415018585418_252535921160899900_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485630043_1235415018585418_252535921160899900_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484774513_1235414718585448_8306078863273257335_n.jpg\"><img decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"11085\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484774513_1235414718585448_8306078863273257335_n-1024x769.jpg\" alt=\"\" class=\"wp-image-11085\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484774513_1235414718585448_8306078863273257335_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484774513_1235414718585448_8306078863273257335_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484774513_1235414718585448_8306078863273257335_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484774513_1235414718585448_8306078863273257335_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484774513_1235414718585448_8306078863273257335_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484940250_1235414781918775_1907656231396489711_n.jpg\"><img decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"11082\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484940250_1235414781918775_1907656231396489711_n-1024x769.jpg\" alt=\"\" class=\"wp-image-11082\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484940250_1235414781918775_1907656231396489711_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484940250_1235414781918775_1907656231396489711_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484940250_1235414781918775_1907656231396489711_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484940250_1235414781918775_1907656231396489711_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484940250_1235414781918775_1907656231396489711_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485138269_1235414698585450_2421292300823143917_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"11081\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485138269_1235414698585450_2421292300823143917_n-1024x769.jpg\" alt=\"\" class=\"wp-image-11081\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485138269_1235414698585450_2421292300823143917_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485138269_1235414698585450_2421292300823143917_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485138269_1235414698585450_2421292300823143917_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485138269_1235414698585450_2421292300823143917_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485138269_1235414698585450_2421292300823143917_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484549540_1235414625252124_3838634253799878853_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"1024\" data-id=\"11083\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484549540_1235414625252124_3838634253799878853_n-769x1024.jpg\" alt=\"\" class=\"wp-image-11083\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484549540_1235414625252124_3838634253799878853_n-769x1024.jpg 769w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484549540_1235414625252124_3838634253799878853_n-225x300.jpg 225w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484549540_1235414625252124_3838634253799878853_n-768x1023.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484549540_1235414625252124_3838634253799878853_n-1153x1536.jpg 1153w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484549540_1235414625252124_3838634253799878853_n.jpg 1537w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484514277_1235414545252132_8983628145197117658_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"11080\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484514277_1235414545252132_8983628145197117658_n-1024x768.jpg\" alt=\"\" class=\"wp-image-11080\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484514277_1235414545252132_8983628145197117658_n-1024x768.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484514277_1235414545252132_8983628145197117658_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484514277_1235414545252132_8983628145197117658_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484514277_1235414545252132_8983628145197117658_n.jpg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484798464_1235414601918793_7335820292576768124_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"11086\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484798464_1235414601918793_7335820292576768124_n-1024x769.jpg\" alt=\"\" class=\"wp-image-11086\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484798464_1235414601918793_7335820292576768124_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484798464_1235414601918793_7335820292576768124_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484798464_1235414601918793_7335820292576768124_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484798464_1235414601918793_7335820292576768124_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484798464_1235414601918793_7335820292576768124_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484786407_1235414408585479_1228434374929119648_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"11087\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484786407_1235414408585479_1228434374929119648_n-1024x769.jpg\" alt=\"\" class=\"wp-image-11087\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484786407_1235414408585479_1228434374929119648_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484786407_1235414408585479_1228434374929119648_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484786407_1235414408585479_1228434374929119648_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484786407_1235414408585479_1228434374929119648_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/484786407_1235414408585479_1228434374929119648_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485764337_1235414271918826_5702987332856789985_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"1024\" data-id=\"11088\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485764337_1235414271918826_5702987332856789985_n-769x1024.jpg\" alt=\"\" class=\"wp-image-11088\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485764337_1235414271918826_5702987332856789985_n-769x1024.jpg 769w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485764337_1235414271918826_5702987332856789985_n-225x300.jpg 225w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485764337_1235414271918826_5702987332856789985_n-768x1023.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485764337_1235414271918826_5702987332856789985_n-1153x1536.jpg 1153w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485764337_1235414271918826_5702987332856789985_n.jpg 1537w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485146939_1235414295252157_2275184352711649158_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-id=\"11089\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485146939_1235414295252157_2275184352711649158_n-1024x769.jpg\" alt=\"\" class=\"wp-image-11089\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485146939_1235414295252157_2275184352711649158_n-1024x769.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485146939_1235414295252157_2275184352711649158_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485146939_1235414295252157_2275184352711649158_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485146939_1235414295252157_2275184352711649158_n-1536x1153.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485146939_1235414295252157_2275184352711649158_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"11090\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n-1024x768.jpg\" alt=\"\" class=\"wp-image-11090\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n-1024x768.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n-300x225.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n-768x576.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n.jpg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2568 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e2b\u0e25\u0e32 \u0e27\u0e07\u0e28\u0e4c\u0e1b\u0e49\u0e2d \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e28.\u0e14\u0e23.\u0e19\u0e34\u0e42\u0e25\u0e1a\u0e25 \u0e27\u0e34\u0e21\u0e25\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e0a\u0e31\u0e22 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14<\/p>\n","protected":false},"author":1,"featured_media":11090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2568 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e2b\u0e25\u0e32 \u0e27\u0e07\u0e28\u0e4c\u0e1b\u0e49\u0e2d \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e28.\u0e14\u0e23.\u0e19\u0e34\u0e42\u0e25\u0e1a\u0e25 \u0e27\u0e34\u0e21\u0e25\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e0a\u0e31\u0e22 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ilaccmru\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-21T02:33:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T02:33:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1477\" \/>\n\t<meta property=\"og:image:height\" content=\"1108\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"weerapich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"weerapich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079\"},\"author\":{\"name\":\"weerapich\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/person\\\/3b7d33d128d6b2fc45aa53883d31a0d8\"},\"headline\":\"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"datePublished\":\"2025-03-21T02:33:57+00:00\",\"dateModified\":\"2025-03-21T02:33:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/485385723_1235413988585521_4225312471658118647_n.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079\",\"name\":\"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/485385723_1235413988585521_4225312471658118647_n.jpg\",\"datePublished\":\"2025-03-21T02:33:57+00:00\",\"dateModified\":\"2025-03-21T02:33:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079#primaryimage\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/485385723_1235413988585521_4225312471658118647_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/485385723_1235413988585521_4225312471658118647_n.jpg\",\"width\":1477,\"height\":1108},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/11079#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/\",\"name\":\"ACI : Arts and Culture Institute\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e21\u0e23\u0e14\u0e01\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-xl.png\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-xl.png\",\"width\":1080,\"height\":1080,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ilaccmru\\\/\",\"https:\\\/\\\/youtube.com\\\/@culturecmru\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/person\\\/3b7d33d128d6b2fc45aa53883d31a0d8\",\"name\":\"weerapich\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"caption\":\"weerapich\"},\"sameAs\":[\"https:\\\/\\\/culture.cmru.ac.th\\\/web\"],\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/author\\\/weerapich\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079","og_locale":"th_TH","og_type":"article","og_title":"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","og_description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2568 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e2b\u0e25\u0e32 \u0e27\u0e07\u0e28\u0e4c\u0e1b\u0e49\u0e2d \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e28.\u0e14\u0e23.\u0e19\u0e34\u0e42\u0e25\u0e1a\u0e25 \u0e27\u0e34\u0e21\u0e25\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e0a\u0e31\u0e22 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14","og_url":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","article_publisher":"https:\/\/www.facebook.com\/ilaccmru\/","article_published_time":"2025-03-21T02:33:57+00:00","article_modified_time":"2025-03-21T02:33:58+00:00","og_image":[{"width":1477,"height":1108,"url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n.jpg","type":"image\/jpeg"}],"author":"weerapich","twitter_card":"summary_large_image","twitter_misc":{"Written by":"weerapich","Est. reading time":"3 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079#article","isPartOf":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079"},"author":{"name":"weerapich","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/person\/3b7d33d128d6b2fc45aa53883d31a0d8"},"headline":"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","datePublished":"2025-03-21T02:33:57+00:00","dateModified":"2025-03-21T02:33:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079#primaryimage"},"thumbnailUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.culture.cmru.ac.th\/web\/th\/11079#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079","url":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079","name":"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","isPartOf":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079#primaryimage"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079#primaryimage"},"thumbnailUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n.jpg","datePublished":"2025-03-21T02:33:57+00:00","dateModified":"2025-03-21T02:33:58+00:00","breadcrumb":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.culture.cmru.ac.th\/web\/th\/11079"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079#primaryimage","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n.jpg","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2025\/03\/485385723_1235413988585521_4225312471658118647_n.jpg","width":1477,"height":1108},{"@type":"BreadcrumbList","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/11079#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.culture.cmru.ac.th\/web\/th\/home"},{"@type":"ListItem","position":2,"name":"\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e13 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1b\u0e48\u0e32\u0e15\u0e38\u0e49\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"}]},{"@type":"WebSite","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#website","url":"https:\/\/www.culture.cmru.ac.th\/web\/","name":"ACI : Arts and Culture Institute","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e21\u0e23\u0e14\u0e01\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19","publisher":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.culture.cmru.ac.th\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","url":"https:\/\/www.culture.cmru.ac.th\/web\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/logo\/image\/","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/logo-xl.png","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/logo-xl.png","width":1080,"height":1080,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ilaccmru\/","https:\/\/youtube.com\/@culturecmru"]},{"@type":"Person","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/person\/3b7d33d128d6b2fc45aa53883d31a0d8","name":"weerapich","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","caption":"weerapich"},"sameAs":["https:\/\/culture.cmru.ac.th\/web"],"url":"https:\/\/www.culture.cmru.ac.th\/web\/author\/weerapich"}]}},"_links":{"self":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts\/11079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/comments?post=11079"}],"version-history":[{"count":0,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts\/11079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/media\/11090"}],"wp:attachment":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/media?parent=11079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/categories?post=11079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/tags?post=11079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}