{"id":7676,"date":"2024-04-29T18:05:00","date_gmt":"2024-04-29T11:05:00","guid":{"rendered":"https:\/\/www.culture.cmru.ac.th\/web\/?p=7676"},"modified":"2025-12-11T09:33:24","modified_gmt":"2025-12-11T02:33:24","slug":"%e0%b8%9e%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b9%80%e0%b8%97%e0%b8%a7%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80%e0%b8%a9%e0%b8%81-%e0%b8%ad%e0%b8%b2%e0%b8%a3%e0%b8%95%e0%b8%b5%e0%b9%84%e0%b8%9f-%e0%b8%ad-2","status":"publish","type":"post","link":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676","title":{"rendered":"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c (\u0e42\u0e2b\u0e25\u0e14\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15) \u0e0a\u0e31\u0e49\u0e19 2 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e21\u0e15\u0e15\u0e32\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e04\u0e23\u0e39\u0e1b\u0e25\u0e31\u0e14\u0e19\u0e31\u0e19\u0e17\u0e27\u0e31\u0e12\u0e19\u0e4c (\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1e\u0e22\u0e38\u0e07\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c) \u0e40\u0e08\u0e49\u0e32\u0e2d\u0e32\u0e27\u0e32\u0e2a\u0e27\u0e31\u0e14\u0e1b\u0e48\u0e32\u0e41\u0e14\u0e14 \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e18\u0e35\u0e1a\u0e27\u0e07\u0e2a\u0e23\u0e27\u0e07\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f\u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23 \u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e42\u0e14\u0e22\u0e1e\u0e34\u0e17\u0e18\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e40\u0e17\u0e27\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e16\u0e32\u0e18\u0e23\u0e23\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e1e\u0e23 \u0e02\u0e19\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e31\u0e01 9 \u0e19\u0e34\u0e49\u0e27 \u0e21\u0e35 4 \u0e01\u0e23<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e23\u0e17\u0e35\u0e48 1 \u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e1e\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e23\u0e34\u0e21\u0e07\u0e04\u0e25\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e32\u0e2a\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e1a\u0e39\u0e0a\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e23\u0e17\u0e35\u0e48 2 \u0e16\u0e37\u0e2d\u0e04\u0e31\u0e21\u0e20\u0e35\u0e23\u0e4c\u0e43\u0e1a\u0e25\u0e32\u0e19 \u0e2d\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e2a\u0e23\u0e23\u0e1e\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e23\u0e17\u0e35\u0e48 3 \u0e16\u0e37\u0e2d\u0e14\u0e2d\u0e01\u0e1a\u0e31\u0e27 \u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c\u0e02\u0e2d\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e34\u0e15\u0e43\u0e08<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e23\u0e17\u0e35\u0e48 4 \u0e16\u0e37\u0e2d\u0e02\u0e19\u0e21\u0e42\u0e21\u0e17\u0e01\u0e30 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e38\u0e13\u0e07\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e31\u0e49\u0e19\u0e42\u0e14\u0e22 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2a\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e1e\u0e23\u0e21\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e13\u0e30\u0e21\u0e19\u0e38\u0e29\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1e\u0e34\u0e18\u0e35\u0e1a\u0e27\u0e07\u0e2a\u0e23\u0e27\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e41\u0e25\u0e30\u0e01\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e10\u0e21\u0e24\u0e01\u0e29\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2566<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a57acad86983&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad902c2&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad902c2\" class=\"wp-block-image size-large wp-lightbox-container\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7680\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438254710_979910987469157_2565317113994343518_n-1024x682.jpg\" alt=\"\" class=\"wp-image-7680\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438254710_979910987469157_2565317113994343518_n-1024x682.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438254710_979910987469157_2565317113994343518_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438254710_979910987469157_2565317113994343518_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438254710_979910987469157_2565317113994343518_n.jpg 1379w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad90d8f&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad90d8f\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7679\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275730_979911427469113_1290988623007713775_n-1024x682.jpg\" alt=\"\" class=\"wp-image-7679\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275730_979911427469113_1290988623007713775_n-1024x682.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275730_979911427469113_1290988623007713775_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275730_979911427469113_1290988623007713775_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275730_979911427469113_1290988623007713775_n.jpg 1379w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad917c7&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad917c7\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7677\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438223683_979911557469100_3044896239089615538_n-1024x682.jpg\" alt=\"\" class=\"wp-image-7677\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438223683_979911557469100_3044896239089615538_n-1024x682.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438223683_979911557469100_3044896239089615538_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438223683_979911557469100_3044896239089615538_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438223683_979911557469100_3044896239089615538_n.jpg 1379w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad92153&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad92153\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7678\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438238915_979911484135774_1341603797740283176_n-1024x682.jpg\" alt=\"\" class=\"wp-image-7678\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438238915_979911484135774_1341603797740283176_n-1024x682.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438238915_979911484135774_1341603797740283176_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438238915_979911484135774_1341603797740283176_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438238915_979911484135774_1341603797740283176_n.jpg 1379w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad92b0a&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad92b0a\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7683\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438255018_979911474135775_1482881767017508191_n-1024x682.jpg\" alt=\"\" class=\"wp-image-7683\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438255018_979911474135775_1482881767017508191_n-1024x682.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438255018_979911474135775_1482881767017508191_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438255018_979911474135775_1482881767017508191_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438255018_979911474135775_1482881767017508191_n.jpg 1379w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad9347b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad9347b\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7681\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438253079_979911097469146_7697012577637688869_n-1024x683.jpg\" alt=\"\" class=\"wp-image-7681\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438253079_979911097469146_7697012577637688869_n-1024x683.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438253079_979911097469146_7697012577637688869_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438253079_979911097469146_7697012577637688869_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438253079_979911097469146_7697012577637688869_n-1536x1024.jpg 1536w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438253079_979911097469146_7697012577637688869_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad93e30&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad93e30\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7682\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438301970_979911727469083_6399746742717123754_n-1024x682.jpg\" alt=\"\" class=\"wp-image-7682\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438301970_979911727469083_6399746742717123754_n-1024x682.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438301970_979911727469083_6399746742717123754_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438301970_979911727469083_6399746742717123754_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438301970_979911727469083_6399746742717123754_n.jpg 1379w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad947d4&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad947d4\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7684\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438305104_979911424135780_3776152168567990179_n-1024x682.jpg\" alt=\"\" class=\"wp-image-7684\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438305104_979911424135780_3776152168567990179_n-1024x682.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438305104_979911424135780_3776152168567990179_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438305104_979911424135780_3776152168567990179_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438305104_979911424135780_3776152168567990179_n.jpg 1379w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad9513f&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad9513f\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7685\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275970_979911170802472_7146991870085990561_n-1024x682.jpg\" alt=\"\" class=\"wp-image-7685\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275970_979911170802472_7146991870085990561_n-1024x682.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275970_979911170802472_7146991870085990561_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275970_979911170802472_7146991870085990561_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438275970_979911170802472_7146991870085990561_n.jpg 1379w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57acad95bc1&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57acad95bc1\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"7686\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n-1024x682.jpg\" alt=\"\" class=\"wp-image-7686\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n-1024x682.jpg 1024w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n-300x200.jpg 300w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n-768x512.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n.jpg 1379w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c (\u0e42\u0e2b\u0e25\u0e14\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15) \u0e0a\u0e31\u0e49\u0e19 2 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/p>\n","protected":false},"author":1,"featured_media":7686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-7676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c (\u0e42\u0e2b\u0e25\u0e14\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15) \u0e0a\u0e31\u0e49\u0e19 2 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c (\u0e42\u0e2b\u0e25\u0e14\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15) \u0e0a\u0e31\u0e49\u0e19 2 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ilaccmru\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T11:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T02:33:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1379\" \/>\n\t<meta property=\"og:image:height\" content=\"919\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"weerapich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"weerapich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676\"},\"author\":{\"name\":\"weerapich\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/person\\\/3b7d33d128d6b2fc45aa53883d31a0d8\"},\"headline\":\"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"datePublished\":\"2024-04-29T11:05:00+00:00\",\"dateModified\":\"2025-12-11T02:33:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/438299232_979910964135826_5084568511898585553_n.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676\",\"name\":\"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/438299232_979910964135826_5084568511898585553_n.jpg\",\"datePublished\":\"2024-04-29T11:05:00+00:00\",\"dateModified\":\"2025-12-11T02:33:24+00:00\",\"description\":\"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c (\u0e42\u0e2b\u0e25\u0e14\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15) \u0e0a\u0e31\u0e49\u0e19 2 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676#primaryimage\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/438299232_979910964135826_5084568511898585553_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/438299232_979910964135826_5084568511898585553_n.jpg\",\"width\":1379,\"height\":919},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7676#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/\",\"name\":\"ACI : Arts and Culture Institute\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e21\u0e23\u0e14\u0e01\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-xl.png\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-xl.png\",\"width\":1080,\"height\":1080,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ilaccmru\\\/\",\"https:\\\/\\\/youtube.com\\\/@culturecmru\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/person\\\/3b7d33d128d6b2fc45aa53883d31a0d8\",\"name\":\"weerapich\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"caption\":\"weerapich\"},\"sameAs\":[\"https:\\\/\\\/culture.cmru.ac.th\\\/web\"],\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/author\\\/weerapich\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","description":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c (\u0e42\u0e2b\u0e25\u0e14\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15) \u0e0a\u0e31\u0e49\u0e19 2 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676","og_locale":"th_TH","og_type":"article","og_title":"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","og_description":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c (\u0e42\u0e2b\u0e25\u0e14\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15) \u0e0a\u0e31\u0e49\u0e19 2 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","og_url":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","article_publisher":"https:\/\/www.facebook.com\/ilaccmru\/","article_published_time":"2024-04-29T11:05:00+00:00","article_modified_time":"2025-12-11T02:33:24+00:00","og_image":[{"width":1379,"height":919,"url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n.jpg","type":"image\/jpeg"}],"author":"weerapich","twitter_card":"summary_large_image","twitter_misc":{"Written by":"weerapich","Est. reading time":"3 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676#article","isPartOf":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676"},"author":{"name":"weerapich","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/person\/3b7d33d128d6b2fc45aa53883d31a0d8"},"headline":"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","datePublished":"2024-04-29T11:05:00+00:00","dateModified":"2025-12-11T02:33:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676#primaryimage"},"thumbnailUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.culture.cmru.ac.th\/web\/th\/7676#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676","url":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676","name":"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","isPartOf":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676#primaryimage"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676#primaryimage"},"thumbnailUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n.jpg","datePublished":"2024-04-29T11:05:00+00:00","dateModified":"2025-12-11T02:33:24+00:00","description":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e32\u0e15\u0e23\u0e35 \u0e21\u0e13\u0e35\u0e42\u0e01\u0e28\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c (\u0e42\u0e2b\u0e25\u0e14\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15) \u0e0a\u0e31\u0e49\u0e19 2 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","breadcrumb":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.culture.cmru.ac.th\/web\/th\/7676"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676#primaryimage","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n.jpg","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/05\/438299232_979910964135826_5084568511898585553_n.jpg","width":1379,"height":919},{"@type":"BreadcrumbList","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7676#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.culture.cmru.ac.th\/web\/th\/home"},{"@type":"ListItem","position":2,"name":"\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 (\u0e2d\u0e32\u0e23\u0e15\u0e35\u0e44\u0e1f) \u0e2d\u0e07\u0e04\u0e4c\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e06\u0e40\u0e19\u0e28\u0e27\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e21\u0e27\u0e25\u0e2a\u0e32\u0e23\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e21\u0e2b\u0e32\u0e21\u0e07\u0e04\u0e25 100 \u0e2d\u0e07\u0e04\u0e4c \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"}]},{"@type":"WebSite","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#website","url":"https:\/\/www.culture.cmru.ac.th\/web\/","name":"ACI : Arts and Culture Institute","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e21\u0e23\u0e14\u0e01\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19","publisher":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.culture.cmru.ac.th\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","url":"https:\/\/www.culture.cmru.ac.th\/web\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/logo\/image\/","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/logo-xl.png","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/logo-xl.png","width":1080,"height":1080,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ilaccmru\/","https:\/\/youtube.com\/@culturecmru"]},{"@type":"Person","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/person\/3b7d33d128d6b2fc45aa53883d31a0d8","name":"weerapich","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","caption":"weerapich"},"sameAs":["https:\/\/culture.cmru.ac.th\/web"],"url":"https:\/\/www.culture.cmru.ac.th\/web\/author\/weerapich"}]}},"_links":{"self":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts\/7676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/comments?post=7676"}],"version-history":[{"count":0,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts\/7676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/media\/7686"}],"wp:attachment":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/media?parent=7676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/categories?post=7676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/tags?post=7676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}