{"id":7911,"date":"2024-06-20T15:45:15","date_gmt":"2024-06-20T08:45:15","guid":{"rendered":"https:\/\/www.culture.cmru.ac.th\/web\/?p=7911"},"modified":"2024-09-10T16:16:56","modified_gmt":"2024-09-10T09:16:56","slug":"%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%a0%e0%b8%b1%e0%b8%8f%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87-3","status":"publish","type":"post","link":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911","title":{"rendered":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" data-id=\"7914\" src=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-724x1024.jpg\" alt=\"\" class=\"wp-image-7914\" srcset=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-724x1024.jpg 724w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-212x300.jpg 212w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-768x1086.jpg 768w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-1086x1536.jpg 1086w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-1448x2048.jpg 1448w, https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg 1810w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e52\u0e55\u0e56\u0e57<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e23\u0e48\u0e27\u0e21\u0e1a\u0e39\u0e0a\u0e32\u0e41\u0e1c\u0e48\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19<\/strong><br>\u0e15\u0e32\u0e21\u0e08\u0e34\u0e15\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e53-\u0e55 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e57 \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e55 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e57 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e59.\u0e53\u0e59 \u0e19. \u0e13 \u0e25\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 (\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e52\u0e57)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e1e\u0e34\u0e18\u0e35\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19<\/strong><br>\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e10\u0e1a\u0e23\u0e34\u0e02\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e49\u0e2d\u0e21\u0e16\u0e27\u0e32\u0e22\u0e22\u0e31\u0e07\u0e27\u0e31\u0e14\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e19\u0e27\u0e19 \u0e51\u0e50 \u0e27\u0e31\u0e14<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e51,\u0e59\u0e59\u0e59 \u0e1a\u0e32\u0e17<\/li>\n\n\n\n<li>\u0e1c\u0e49\u0e32\u0e44\u0e15\u0e23\u0e08\u0e35\u0e27\u0e23 \u0e59\u0e59\u0e59 \u0e1a\u0e32\u0e17<\/li>\n\n\n\n<li>\u0e2a\u0e31\u0e07\u0e06\u0e17\u0e32\u0e19 \u0e57\u0e59\u0e59 \u0e1a\u0e32\u0e17<\/li>\n\n\n\n<li>\u0e1c\u0e49\u0e32\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e2d\u0e14\u0e44\u0e1f \u0e54\u0e59\u0e59 \u0e1a\u0e32\u0e17<\/li>\n\n\n\n<li>\u0e15\u0e32\u0e21\u0e08\u0e34\u0e15\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21<br>\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21 \u0e04\u0e38\u0e13\u0e14\u0e32\u0e23\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e28\u0e34\u0e23\u0e34\u0e25\u0e32\u0e20\u0e32<br>\u0e42\u0e17\u0e23 \u0e50\u0e58\u0e59-\u0e54\u0e53\u0e51\u0e59\u0e52\u0e50\u0e50<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>&#8220;\u0e2d\u0e32\u0e19\u0e34\u0e2a\u0e07\u0e2a\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32<br>\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e15\u0e34 \u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e2d\u0e32\u0e22\u0e38 \u0e27\u0e23\u0e23\u0e13\u0e30 \u0e2a\u0e38\u0e02\u0e30 \u0e1e\u0e25\u0e30 \u0e1b\u0e0f\u0e34\u0e20\u0e32\u0e13 \u0e18\u0e19\u0e2a\u0e32\u0e23\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23&#8221;<\/em><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e  [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-7911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\" \/>\n<meta property=\"og:description\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ilaccmru\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T08:45:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T09:16:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"weerapich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"weerapich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911\"},\"author\":{\"name\":\"weerapich\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/person\\\/3b7d33d128d6b2fc45aa53883d31a0d8\"},\"headline\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32\",\"datePublished\":\"2024-06-20T08:45:15+00:00\",\"dateModified\":\"2024-09-10T09:16:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911\"},\"wordCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg\",\"datePublished\":\"2024-06-20T08:45:15+00:00\",\"dateModified\":\"2024-09-10T09:16:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911#primaryimage\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg\",\"width\":1810,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/7911#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/th\\\/home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/\",\"name\":\"ACI : Arts and Culture Institute\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e21\u0e23\u0e14\u0e01\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-xl.png\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-xl.png\",\"width\":1080,\"height\":1080,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\"},\"image\":{\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ilaccmru\\\/\",\"https:\\\/\\\/youtube.com\\\/@culturecmru\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/#\\\/schema\\\/person\\\/3b7d33d128d6b2fc45aa53883d31a0d8\",\"name\":\"weerapich\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/358136754_777108407749417_7321447843382332083_n-150x150.jpg\",\"caption\":\"weerapich\"},\"sameAs\":[\"https:\\\/\\\/culture.cmru.ac.th\\\/web\"],\"url\":\"https:\\\/\\\/www.culture.cmru.ac.th\\\/web\\\/author\\\/weerapich\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911","og_locale":"th_TH","og_type":"article","og_title":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","og_description":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e [&hellip;]","og_url":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","article_publisher":"https:\/\/www.facebook.com\/ilaccmru\/","article_published_time":"2024-06-20T08:45:15+00:00","article_modified_time":"2024-09-10T09:16:56+00:00","og_image":[{"width":1810,"height":2560,"url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg","type":"image\/jpeg"}],"author":"weerapich","twitter_card":"summary_large_image","twitter_misc":{"Written by":"weerapich","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911#article","isPartOf":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911"},"author":{"name":"weerapich","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/person\/3b7d33d128d6b2fc45aa53883d31a0d8"},"headline":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32","datePublished":"2024-06-20T08:45:15+00:00","dateModified":"2024-09-10T09:16:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911"},"wordCount":2,"publisher":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911#primaryimage"},"thumbnailUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911","url":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 - ACI : Arts and Culture Institute","isPartOf":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911#primaryimage"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911#primaryimage"},"thumbnailUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg","datePublished":"2024-06-20T08:45:15+00:00","dateModified":"2024-09-10T09:16:56+00:00","breadcrumb":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.culture.cmru.ac.th\/web\/th\/7911"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911#primaryimage","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/06\/\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e-\u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e2b\u0e48\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32-2567-copy-2-scaled.jpg","width":1810,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.culture.cmru.ac.th\/web\/th\/7911#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.culture.cmru.ac.th\/web\/th\/home"},{"@type":"ListItem","position":2,"name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e1e\u0e34\u0e18\u0e35\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e16\u0e27\u0e32\u0e22\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e23\u0e29\u0e32"}]},{"@type":"WebSite","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#website","url":"https:\/\/www.culture.cmru.ac.th\/web\/","name":"ACI : Arts and Culture Institute","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e21\u0e23\u0e14\u0e01\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19","publisher":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.culture.cmru.ac.th\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","url":"https:\/\/www.culture.cmru.ac.th\/web\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/logo\/image\/","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/logo-xl.png","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/logo-xl.png","width":1080,"height":1080,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ilaccmru\/","https:\/\/youtube.com\/@culturecmru"]},{"@type":"Person","@id":"https:\/\/www.culture.cmru.ac.th\/web\/#\/schema\/person\/3b7d33d128d6b2fc45aa53883d31a0d8","name":"weerapich","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","url":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","contentUrl":"https:\/\/www.culture.cmru.ac.th\/web\/wp-content\/uploads\/2024\/03\/358136754_777108407749417_7321447843382332083_n-150x150.jpg","caption":"weerapich"},"sameAs":["https:\/\/culture.cmru.ac.th\/web"],"url":"https:\/\/www.culture.cmru.ac.th\/web\/author\/weerapich"}]}},"_links":{"self":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts\/7911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/comments?post=7911"}],"version-history":[{"count":0,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/posts\/7911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/media\/7914"}],"wp:attachment":[{"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/media?parent=7911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/categories?post=7911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web\/wp-json\/wp\/v2\/tags?post=7911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}