{"id":7528,"date":"2021-01-25T10:14:32","date_gmt":"2021-01-25T03:14:32","guid":{"rendered":"http:\/\/www.culture.cmru.ac.th\/web60\/?page_id=7528"},"modified":"2021-01-27T15:23:42","modified_gmt":"2021-01-27T08:23:42","slug":"%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c","status":"publish","type":"page","link":"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/","title":{"rendered":"\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22"},"content":{"rendered":"<h2><em><strong>\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e43\u0e19\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 <\/strong><\/em><\/h2>\n<h2><strong><em>\u0e01\u0e32\u0e23\u0e08\u0e33\u0e41\u0e19\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c<\/em><\/strong><\/h2>\n<h3><strong>\u0e51<\/strong><strong>.\u00a0 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e20\u0e32\u0e29\u0e32<\/strong><\/h3>\n<p>\u0e51.\u0e51 \u00a0\u0e2d\u0e2d\u0e2a\u0e42\u0e15\u0e23\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e34\u0e01 \u00a0(Austro Asiatic Languages) \u00a0\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e43\u0e15\u0e49 \u0e2d\u0e35\u0e01\u0e0a\u0e37\u0e48\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e04\u0e37\u0e2d <strong>\u201c\u0e21\u0e2d\u0e0d-\u0e40\u0e02\u0e21\u0e23\u201d <\/strong>\u0e20\u0e32\u0e29\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21\u0e43\u0e2b\u0e0d\u0e48\u0e43\u0e19\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49 \u0e41\u0e25\u0e30\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e07\u0e01\u0e25\u0e32\u0e40\u0e17\u0e28 \u0e20\u0e32\u0e29\u0e32\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e43\u0e19\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u00a0 \u0e43\u0e19\u0e1a\u0e23\u0e23\u0e14\u0e32\u0e20\u0e32\u0e29\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21 \u0e20\u0e32\u0e29\u0e32\u0e40\u0e02\u0e21\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e32\u0e21\u0e2d\u0e0d\u0e40\u0e1b\u0e47\u0e19 \u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u00a0 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e37\u0e2d <strong>\u0e25\u0e31\u0e27\u0e30 <\/strong><strong>(<\/strong><strong>LUA)<\/strong><\/p>\n<p>\u0e51.\u0e52 \u00a0\u0e44\u0e17 \u2013 \u0e01\u0e30\u0e44\u0e14 (Tai \u2013 Kadai\u00a0 Languages)\u00a0 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e27\u0e23\u0e23\u0e13\u0e22\u0e38\u0e01\u0e15\u0e4c \u0e1e\u0e1a\u0e43\u0e19\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e41\u0e25\u0e30\u0e15\u0e2d\u0e19\u0e43\u0e15\u0e49\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 \u00a0\u00a0\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e37\u0e2d <strong>\u0e44\u0e17\u0e43\u0e2b\u0e0d\u0e48 \u00a0\u0e44\u0e17\u0e25\u0e37\u0e49\u0e2d \u0e44\u0e17\u0e02\u0e36\u0e19\/\u0e44\u0e17\u0e40\u0e02\u0e34\u0e19\u00a0 \u0e44\u0e17\u0e22\u0e2d\u0e07\u00a0\u00a0 \u0e44\u0e17\u0e22\u0e27\u0e19\u00a0 <\/strong>\u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07 \u0e44\u0e17\u0e14\u0e33\/\u0e25\u0e32\u0e27\u0e42\u0e0b\u0e48\u0e07\u00a0 \u0e44\u0e17\u0e22\u00a0\u00a0 \u0e1c\u0e39\u0e49\u0e44\u0e17\u00a0 \u0e1e\u0e27\u0e19\u00a0 \u0e25\u0e32\u0e27\u00a0 \u0e25\u0e32\u0e27\u0e41\u0e07\u0e49\u0e27 \u0e41\u0e2a\u0e01\u00a0 \u0e25\u0e32\u0e27\u0e04\u0e23\u0e31\u0e48\u0e07<\/p>\n<p>\u0e51.\u0e53\u00a0 \u0e08\u0e35\u0e19 \u2013 \u0e17\u0e34\u0e40\u0e1a\u0e15\u00a0 (Sino \u2013 Tibetan Language) \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19\u0e41\u0e25\u0e30\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e20\u0e32\u0e29\u0e32\u0e22\u0e48\u0e2d\u0e22\u0e17\u0e34\u0e40\u0e1a\u0e15 \u2013 \u0e1e\u0e21\u0e48\u0e32 \u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e52\u0e55\u0e50 \u0e20\u0e32\u0e29\u0e32 \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e29\u0e32\u0e43\u0e19\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u00a0 \u0e20\u0e32\u0e29\u0e32\u0e43\u0e19\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e19\u0e35\u0e49\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e21\u0e35\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e27\u0e23\u0e23\u0e13\u0e22\u0e38\u0e01\u0e15\u0e4c\u00a0 \u0e1e\u0e1a\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e08\u0e35\u0e19\u0e2e\u0e48\u0e2d \u0e01\u0e30\u0e40\u0e2b\u0e23\u0e35\u0e48\u0e22\u0e07 \u0e25\u0e35\u0e0b\u0e2d\u00a0 \u0e21\u0e39\u0e40\u0e0b\u0e2d\u00a0 \u0e2d\u0e32\u0e02\u0e48\u0e32 \u0e2d\u0e35\u0e01\u0e49\u0e2d<\/p>\n<p>\u0e51.\u0e54\u00a0 \u0e2d\u0e2d\u0e2a\u0e42\u0e15\u0e23\u0e40\u0e19\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19\u00a0 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e1e\u0e39\u0e14\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e44\u0e1b\u0e17\u0e31\u0e48\u0e27\u0e2b\u0e21\u0e39\u0e48\u0e40\u0e01\u0e32\u0e30\u0e43\u0e19\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e41\u0e25\u0e30\u0e21\u0e2b\u0e32\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e19\u0e49\u0e2d\u0e22\u0e1a\u0e19\u0e1c\u0e37\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e27\u0e35\u0e1b\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e21\u0e04\u0e33\u0e27\u0e48\u0e32 Austro \u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e25\u0e21\u0e43\u0e15\u0e49 \u0e23\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e01\u0e23\u0e35\u0e01 nesos \u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e40\u0e01\u0e32\u0e30\u00a0 \u0e40\u0e0a\u0e48\u0e19 \u0e20\u0e32\u0e29\u0e32\u0e21\u0e32\u0e40\u0e25\u0e22\u0e4c \u0e20\u0e32\u0e29\u0e32\u0e08\u0e32\u0e21 \u0e20\u0e32\u0e29\u0e32\u0e21\u0e2d\u0e40\u0e01\u0e47\u0e19 (Moken)<\/p>\n<p>\u0e51.\u0e55 \u00a0\u0e21\u0e49\u0e07 \u2013 \u0e40\u0e21\u0e35\u0e48\u0e22\u0e19\u00a0\u00a0 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e20\u0e32\u0e29\u0e32\u0e40\u0e25\u0e47\u0e01\u0e46\u00a0 \u0e43\u0e0a\u0e49\u0e01\u0e31\u0e19\u0e17\u0e32\u0e07\u0e15\u0e2d\u0e19\u0e43\u0e15\u0e49\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49 \u0e43\u0e0a\u0e49\u0e1e\u0e39\u0e14\u0e01\u0e31\u0e19\u0e43\u0e19\u0e41\u0e16\u0e1a\u0e20\u0e39\u0e40\u0e02\u0e32\u0e2a\u0e39\u0e07\u0e15\u0e2d\u0e19\u0e43\u0e15\u0e49\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e21\u0e13\u0e11\u0e25\u0e01\u0e38\u0e49\u0e22\u0e42\u0e08\u0e27 \u0e2b\u0e39\u0e2b\u0e19\u0e32\u0e19 \u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e40\u0e2a\u0e09\u0e27\u0e19 \u0e01\u0e27\u0e32\u0e07\u0e2a\u0e35\u00a0 \u0e41\u0e25\u0e30\u0e21\u0e13\u0e11\u0e25\u0e2b\u0e39\u0e40\u0e1b\u0e48\u0e22 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 \u201c\u0e0a\u0e32\u0e27\u0e40\u0e02\u0e32\u201d \u00a0\u0e1e\u0e1a\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e40\u0e21\u0e35\u0e48\u0e22\u0e19 \/\u0e40\u0e22\u0e49\u0e32\u00a0 \u0e41\u0e25\u0e30 \u0e21\u0e49\u0e07 \/\u0e41\u0e21\u0e49\u0e27<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u0e52.\u00a0 \u0e15\u0e33\u0e19\u0e32\u0e19\u00a0 \u00a0<\/strong><\/h3>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e15\u0e33\u0e19\u0e32\u0e19\u0e19\u0e49\u0e33\u0e40\u0e15\u0e49\u0e32\u0e1b\u0e38\u0e07<\/strong> \u00a0\u0e15\u0e33\u0e19\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e43\u0e19\u0e41\u0e16\u0e1a\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e25\u0e48\u0e32\u0e16\u0e36\u0e07\u0e15\u0e33\u0e19\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e40\u0e1c\u0e48\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e14\u0e34\u0e19\u0e22\u0e31\u0e07\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e1c\u0e35\u0e41\u0e25\u0e30\u0e04\u0e19\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e1b\u0e21\u0e32\u0e2b\u0e32\u0e2a\u0e39\u0e48\u0e01\u0e31\u0e19 \u0e1a\u0e19\u0e1f\u0e32\u0e01\u0e1f\u0e49\u0e32\u0e21\u0e35\u0e41\u0e16\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e2b\u0e0d\u0e48 \u0e1a\u0e19\u0e14\u0e34\u0e19\u0e21\u0e35\u0e02\u0e38\u0e19\u0e04\u0e32\u0e19\u0e1b\u0e25\u0e39\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e25\u0e38\u0e48\u0e21\u00a0 \u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e31\u0e49\u0e19\u0e41\u0e16\u0e19\u0e44\u0e14\u0e49\u0e1a\u0e2d\u0e01\u0e41\u0e01\u0e48\u0e02\u0e38\u0e19\u0e04\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e2d\u0e01\u0e01\u0e25\u0e48\u0e32\u0e27\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e27\u0e48\u0e32 \u0e2b\u0e32\u0e01\u0e08\u0e30\u0e17\u0e33\u0e2d\u0e30\u0e44\u0e23\u0e15\u0e48\u0e2d\u0e14\u0e34\u0e19\u0e1f\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e2d\u0e01\u0e01\u0e25\u0e48\u0e32\u0e27\u0e41\u0e01\u0e48\u0e41\u0e16\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e48\u0e07\u0e1b\u0e25\u0e32\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e16\u0e19\u0e1a\u0e19\u0e1f\u0e32\u0e01\u0e1f\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22<br \/>\n\u0e41\u0e15\u0e48&#8230;\u0e21\u0e32\u0e16\u0e36\u0e07\u0e2a\u0e21\u0e31\u0e22\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e21\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1f\u0e31\u0e07\u0e41\u0e16\u0e19\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e22\u0e2d\u0e21\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e41\u0e16\u0e19\u0e40\u0e04\u0e22\u0e2a\u0e31\u0e48\u0e07\u0e44\u0e27\u0e49 \u00a0\u00a0\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e41\u0e16\u0e19\u0e08\u0e30\u0e25\u0e07\u0e21\u0e32\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e04\u0e23\u0e32 \u00a0\u00a0\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e32\u0e27\u0e1b\u0e25\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e16\u0e19\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e33\u0e1e\u0e32&#8230; \u0e41\u0e16\u0e19\u0e08\u0e36\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e40\u0e21\u0e37\u0e2d\u0e07\u00a0 \u00a0\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e1e\u0e32\u0e01\u0e31\u0e19\u0e25\u0e49\u0e21\u0e15\u0e32\u0e22\u0e09\u0e34\u0e1a\u0e2b\u0e32\u0e22\u0e2b\u0e21\u0e14\u00a0 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e19\u0e31\u0e49\u0e19\u0e02\u0e38\u0e19\u0e04\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e23\u0e27\u0e21 \u0e53 \u0e04\u0e19 \u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e41\u0e16\u0e19\u0e42\u0e01\u0e23\u0e18 \u0e08\u0e36\u0e07\u0e1e\u0e32\u0e01\u0e31\u0e19\u0e15\u0e48\u0e2d\u0e41\u0e1e\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e22\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e2b\u0e32\u0e41\u0e16\u0e19\u0e1a\u0e19\u0e1f\u0e49\u0e32 \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46\u0e43\u0e2b\u0e49\u0e41\u0e16\u0e19\u0e1f\u0e31\u0e07 \u0e41\u0e16\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e41\u0e25\u0e49\u0e27\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e44\u0e21\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1f\u0e31\u0e07\u0e15\u0e19 \u0e02\u0e38\u0e19\u0e04\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e1d\u0e49\u0e32\u0e41\u0e16\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e19\u0e49\u0e33\u0e25\u0e14 \u0e08\u0e36\u0e07\u0e02\u0e2d\u0e25\u0e32\u0e41\u0e16\u0e19\u0e25\u0e07\u0e21\u0e32\u0e22\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e25\u0e38\u0e48\u0e21 \u0e41\u0e16\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e22\u0e25\u0e07\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e53 \u0e15\u0e31\u0e27 \u0e02\u0e38\u0e19\u0e17\u0e31\u0e49\u0e07 \u0e53\u00a0 \u0e17\u0e33\u0e19\u0e32\u0e44\u0e14\u0e49 \u0e53 \u0e1b\u0e35 \u0e04\u0e27\u0e32\u0e22\u0e01\u0e47\u0e15\u0e32\u0e22 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e01\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e2b\u0e21\u0e32\u0e01\u0e19\u0e49\u0e33\u0e40\u0e15\u0e49\u0e32 \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e39\u0e08\u0e21\u0e39\u0e01\u0e04\u0e27\u0e32\u0e22\u0e16\u0e36\u0e07 \u0e53 \u0e25\u0e39\u0e01 \u0e21\u0e35\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e19\u0e49\u0e33\u0e40\u0e15\u0e49\u0e32\u0e19\u0e31\u0e49\u0e19\u0e1b\u0e39\u0e48\u0e25\u0e32\u0e07\u0e40\u0e0a\u0e34\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e22\u0e34\u0e1a\u0e40\u0e2d\u0e32\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e1b\u0e40\u0e08\u0e32\u0e30 \u0e40\u0e01\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e2d\u0e2d\u0e01\u0e21\u0e32 \u0e52 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e04\u0e37\u0e2d \u0e44\u0e17\u0e22\u0e25\u0e21\u0e41\u0e25\u0e30\u0e44\u0e17\u0e22\u0e25\u0e35\u00a0 \u0e02\u0e38\u0e19\u0e04\u0e32\u0e19\u0e08\u0e36\u0e07\u0e19\u0e33\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2d\u0e35\u0e01\u0e17\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e44\u0e1b\u0e40\u0e08\u0e32\u0e30\u0e2d\u0e35\u0e01\u0e23\u0e39\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e40\u0e15\u0e49\u0e32 \u0e08\u0e36\u0e07\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e17\u0e40\u0e25\u0e34\u0e07 \u0e44\u0e17\u0e25\u0e2d \u0e41\u0e25\u0e30\u0e44\u0e17\u0e04\u0e27\u0e07\u00a0 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e23\u0e39\u0e19\u0e49\u0e33\u0e40\u0e15\u0e49\u0e32\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e01\u0e47\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e04\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e23\u0e39\u0e40\u0e25\u0e47\u0e01\u0e01\u0e27\u0e48\u0e32\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32 \u0e2a\u0e48\u0e27\u0e19\u0e04\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e39\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e27\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e17\u0e04\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e25\u0e39\u0e01\u0e2b\u0e25\u0e32\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u00a0 \u0e17\u0e33\u0e21\u0e32\u0e2b\u0e32\u0e01\u0e34\u0e19\u0e01\u0e31\u0e19\u0e21\u0e32\u0e40\u0e19\u0e34\u0e48\u0e19\u0e19\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e44\u0e21\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1f\u0e31\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e41\u0e16\u0e19\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e34\u0e21\u00a0 \u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e1c\u0e37\u0e19\u0e14\u0e34\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e21 \u0e08\u0e36\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e40\u0e1d\u0e49\u0e32\u0e41\u0e16\u0e19\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u00a0 \u0e41\u0e16\u0e19\u0e08\u0e36\u0e07\u0e2a\u0e48\u0e07\u0e02\u0e38\u0e19\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e02\u0e38\u0e19\u0e04\u0e23\u0e2d\u0e07 \u0e25\u0e07\u0e21\u0e32 \u0e41\u0e15\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e27\u0e48\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e21\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e1e\u0e23\u0e48\u0e1f\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e38\u0e01\u0e02\u0e4c\u0e01\u0e31\u0e19\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u00a0 \u0e02\u0e38\u0e19\u0e04\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e23\u0e04\u0e1e\u0e27\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e40\u0e1d\u0e49\u0e32\u0e41\u0e16\u0e19\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e02\u0e38\u0e19\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e02\u0e38\u0e19\u0e04\u0e23\u0e2d\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e16\u0e19\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e41\u0e16\u0e19\u0e08\u0e36\u0e07\u0e2a\u0e48\u0e07\u0e02\u0e38\u0e19\u0e1a\u0e39\u0e25\u0e21 \u0e25\u0e07\u0e21\u0e32\u0e17\u0e35\u0e48\u0e19\u0e32\u0e19\u0e49\u0e2d\u0e22 \u0e2d\u0e49\u0e2d\u0e22\u0e2b\u0e19\u0e39 \u00a0\u0e02\u0e38\u0e19\u0e1a\u0e39\u0e25\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e1b\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e21\u0e35\u0e25\u0e39\u0e01 \u0e57 \u0e04\u0e19 \u0e2a\u0e48\u0e07\u0e44\u0e1b\u0e04\u0e23\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e16\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e1a\u0e19\u0e1c\u0e37\u0e19\u0e14\u0e34\u0e19\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e16\u0e19\u0e1a\u0e19\u0e1f\u0e32\u0e01\u0e1f\u0e49\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e35\u0e41\u0e25\u0e30\u0e04\u0e19\u0e44\u0e1b\u0e21\u0e32\u0e2b\u0e32\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b&#8230;.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>\u0e53.\u00a0 \u0e2d\u0e31\u0e15\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c<\/strong><\/h3>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e23\u0e27\u0e21\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e08\u0e33\u0e41\u0e19\u0e01\u0e14\u0e49\u0e27\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e01\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e19\u0e43\u0e19\u0e43\u0e0a\u0e49\u0e40\u0e23\u0e35\u0e22\u0e01\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e1e\u0e1a\u0e27\u0e48\u0e32 <strong>\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e21\u0e35\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e56\u0e52 \u0e01\u0e25\u0e38\u0e48\u0e21 <\/strong>\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e01\u0e08\u0e33\u0e41\u0e2b\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e43\u0e19\u0e20\u0e32\u0e27\u0e30\u0e27\u0e34\u0e01\u0e24\u0e15 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 <strong>\u0e21\u0e35\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32 \u0e43\u0e19\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e55 \u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 \u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e57\u0e50 \u0e01\u0e25\u0e38\u0e48\u0e21<\/strong><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_7528\" class=\"pvc_stats all  \" data-element-id=\"7528\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.culture.cmru.ac.th\/web60\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e43\u0e19\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e41\u0e19\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e51.\u00a0 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e20\u0e32\u0e29 [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_7528\" class=\"pvc_stats all  \" data-element-id=\"7528\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.culture.cmru.ac.th\/web60\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_7528\" class=\"pvc_stats all  \" data-element-id=\"7528\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.culture.cmru.ac.th\/web60\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":0,"parent":7464,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-leftbar2.php","meta":{"footnotes":""},"class_list":["post-7528","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\" \/>\n<meta property=\"og:description\" content=\"\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e43\u0e19\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e41\u0e19\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e51.\u00a0 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e20\u0e32\u0e29 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ilaccmru\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-27T08:23:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/\",\"url\":\"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/\",\"name\":\"\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\",\"isPartOf\":{\"@id\":\"https:\/\/www.culture.cmru.ac.th\/web60\/#website\"},\"datePublished\":\"2021-01-25T03:14:32+00:00\",\"dateModified\":\"2021-01-27T08:23:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.culture.cmru.ac.th\/web60\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e04\u0e25\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\",\"item\":\"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.culture.cmru.ac.th\/web60\/#website\",\"url\":\"https:\/\/www.culture.cmru.ac.th\/web60\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\",\"description\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"publisher\":{\"@id\":\"https:\/\/www.culture.cmru.ac.th\/web60\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.culture.cmru.ac.th\/web60\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.culture.cmru.ac.th\/web60\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"url\":\"https:\/\/www.culture.cmru.ac.th\/web60\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.culture.cmru.ac.th\/web60\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.culture.cmru.ac.th\/web60\/wp-content\/uploads\/2017\/06\/culture-logo.png\",\"contentUrl\":\"http:\/\/www.culture.cmru.ac.th\/web60\/wp-content\/uploads\/2017\/06\/culture-logo.png\",\"width\":104,\"height\":147,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\"},\"image\":{\"@id\":\"https:\/\/www.culture.cmru.ac.th\/web60\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ilaccmru\/\",\"https:\/\/www.youtube.com\/c\/culturecmru\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","og_description":"\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e43\u0e19\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e41\u0e19\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e51.\u00a0 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e20\u0e32\u0e29 [&hellip;]","og_url":"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","article_publisher":"https:\/\/www.facebook.com\/ilaccmru\/","article_modified_time":"2021-01-27T08:23:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/","url":"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/","name":"\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","isPartOf":{"@id":"https:\/\/www.culture.cmru.ac.th\/web60\/#website"},"datePublished":"2021-01-25T03:14:32+00:00","dateModified":"2021-01-27T08:23:42+00:00","breadcrumb":{"@id":"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/%e0%b8%99%e0%b8%b4%e0%b8%97%e0%b8%a3%e0%b8%a3%e0%b8%a8%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8a%e0%b8%b2%e0%b8%95%e0%b8%b4%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b8%b8%e0%b9%8c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.culture.cmru.ac.th\/web60\/"},{"@type":"ListItem","position":2,"name":"\u0e04\u0e25\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","item":"https:\/\/www.culture.cmru.ac.th\/web60\/learningcenter\/"},{"@type":"ListItem","position":3,"name":"\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22"}]},{"@type":"WebSite","@id":"https:\/\/www.culture.cmru.ac.th\/web60\/#website","url":"https:\/\/www.culture.cmru.ac.th\/web60\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21","description":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","publisher":{"@id":"https:\/\/www.culture.cmru.ac.th\/web60\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.culture.cmru.ac.th\/web60\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.culture.cmru.ac.th\/web60\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","url":"https:\/\/www.culture.cmru.ac.th\/web60\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.culture.cmru.ac.th\/web60\/#\/schema\/logo\/image\/","url":"http:\/\/www.culture.cmru.ac.th\/web60\/wp-content\/uploads\/2017\/06\/culture-logo.png","contentUrl":"http:\/\/www.culture.cmru.ac.th\/web60\/wp-content\/uploads\/2017\/06\/culture-logo.png","width":104,"height":147,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"},"image":{"@id":"https:\/\/www.culture.cmru.ac.th\/web60\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ilaccmru\/","https:\/\/www.youtube.com\/c\/culturecmru"]}]}},"_links":{"self":[{"href":"https:\/\/www.culture.cmru.ac.th\/web60\/wp-json\/wp\/v2\/pages\/7528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culture.cmru.ac.th\/web60\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.culture.cmru.ac.th\/web60\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web60\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web60\/wp-json\/wp\/v2\/comments?post=7528"}],"version-history":[{"count":6,"href":"https:\/\/www.culture.cmru.ac.th\/web60\/wp-json\/wp\/v2\/pages\/7528\/revisions"}],"predecessor-version":[{"id":7789,"href":"https:\/\/www.culture.cmru.ac.th\/web60\/wp-json\/wp\/v2\/pages\/7528\/revisions\/7789"}],"up":[{"embeddable":true,"href":"https:\/\/www.culture.cmru.ac.th\/web60\/wp-json\/wp\/v2\/pages\/7464"}],"wp:attachment":[{"href":"https:\/\/www.culture.cmru.ac.th\/web60\/wp-json\/wp\/v2\/media?parent=7528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}